{"id":4053,"date":"2021-04-19T12:03:43","date_gmt":"2021-04-19T12:03:43","guid":{"rendered":"https:\/\/aktionvierviertel.ch\/?page_id=4053"},"modified":"2021-10-27T13:47:01","modified_gmt":"2021-10-27T13:47:01","slug":"hinweise-zum-datenschutz","status":"publish","type":"page","link":"https:\/\/aktionvierviertel.ch\/fr\/politique-de-confidentialite\/","title":{"rendered":"Politique de confidentialit\u00e9"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"4053\" class=\"elementor elementor-4053\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"has_ae_slider elementor-section elementor-top-section elementor-element elementor-element-6571fe6 elementor-section-full_width elementor-section-height-default elementor-section-height-default ae-bg-gallery-type-default\" data-id=\"6571fe6\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7036767 ae-bg-gallery-type-default\" data-id=\"7036767\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"has_ae_slider elementor-section elementor-inner-section elementor-element elementor-element-f2014bf elementor-section-full_width elementor-section-height-default elementor-section-height-default ae-bg-gallery-type-default\" data-id=\"f2014bf\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-f720fff ae-bg-gallery-type-default\" data-id=\"f720fff\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3478fe0 elementor-widget elementor-widget-heading\" data-id=\"3478fe0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Politique de confidentialit\u00e9\n<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_ae_slider elementor-section elementor-inner-section elementor-element elementor-element-4f93bbf elementor-section-full_width purple-link elementor-section-height-default elementor-section-height-default ae-bg-gallery-type-default\" data-id=\"4f93bbf\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-52617fd ae-bg-gallery-type-default\" data-id=\"52617fd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-96d0fef elementor-widget elementor-widget-text-editor\" data-id=\"96d0fef\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">AKTION VIERVIERTEL, dont le si\u00e8ge social est situ\u00e9 sis 8000 Zurich, collecte, traite, stocke et prot\u00e8ge les donn\u00e9es des personnes qui acc\u00e8dent au site www.aktionvierviertel.ch (\"utilisateurs\"). Par le biais de cette d\u00e9claration de protection des donn\u00e9es, AKTION VIERVIERTEL souhaite informer les utilisatrices-eurs des droits auxquels elles-ils peuvent pr\u00e9tendre et informer le public de la nature, de la port\u00e9e et de la finalit\u00e9 des donn\u00e9es personnelles collect\u00e9es, utilis\u00e9es et trait\u00e9es.<\/span><\/p><p><span style=\"font-weight: 400;\">L'utilisation du site www. aktionvierviertel.ch est possible sans indication de donn\u00e9es personnelles. Toutefois, si un utilisateur souhaite utiliser des services particuliers via le site web www.aktionvierviertel.ch, le traitement des donn\u00e9es personnelles pourrait devenir n\u00e9cessaire. Si le traitement des donn\u00e9es personnelles est n\u00e9cessaire et qu'il n'existe pas de base juridique pour ce traitement, le consentement de l'utilisateur sera obtenu.<\/span><\/p><p><span style=\"font-weight: 400;\">Le traitement des donn\u00e9es personnelles, par exemple le nom et l'adresse \u00e9lectronique d'un utilisateur, est toujours effectu\u00e9 conform\u00e9ment aux exigences l\u00e9gales. Aktion Vierviertel est soumis \u00e0 la loi suisse sur la protection des donn\u00e9es.<\/span><\/p><p><span style=\"font-weight: 400;\">Toutefois, si des donn\u00e9es personnelles de citoyens de l'UE sont trait\u00e9es, le R\u00e8glement europ\u00e9en sur la protection des donn\u00e9es (RGPD) (UE\/2016\/679) s'applique. \u00c9tant donn\u00e9 que le r\u00e8glement stipule en partie des droits et obligations plus \u00e9tendu-e-s en faveur de l'utilisateur, ces derni\u00e8r-e-s sont \u00e9galement appliqu\u00e9-e-s aux utilisateurs qui r\u00e9sident en Suisse.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c6d9bf simple-accordeon toggle-hover2 elementor-widget elementor-widget-accordion\" data-id=\"7c6d9bf\" data-element_type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1301\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1301\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">1. Nom et adresse du responsable du site<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1301\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1301\"><p><span style=\"font-weight: 400;\">Le responsable du site Internet www.aktionvierviertel.ch est Aktion Vierviertel avec les coordonn\u00e9es suivantes :<\/span><\/p><p><b>Action Quatre Quarts<\/b><span style=\"font-weight: 400;\"><br \/><\/span><span style=\"font-weight: 400;\">8000 Z\u00fcrich<\/span><\/p><p><span style=\"font-weight: 400;\">Suisse<\/span><span style=\"font-weight: 400;\"><br \/><\/span><span style=\"font-weight: 400;\">Email : kontakt@aktionvierviertel.ch<\/span><span style=\"font-weight: 400;\"><br \/><\/span><span style=\"font-weight: 400;\">Site Internet : <\/span><a href=\"https:\/\/aktionvierviertel.ch\/fr\/\"><span style=\"font-weight: 400;\">www.aktionvierviertel.ch\/fr<\/span><\/a><\/p><p><span style=\"font-weight: 400;\">Vous pouvez contacter notre d\u00e9l\u00e9gu\u00e9-e \u00e0 la protection des donn\u00e9es \u00e0 l'adresse\u00a0<\/span><a href=\"mailto:datenschutz@aktionvierviertel.ch\"><span style=\"font-weight: 400;\">datenschutz@aktionvierviertel.ch<\/span><\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1302\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1302\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">2. Cookies<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1302\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1302\"><p><span style=\"font-weight: 400;\">Le site www.aktionvierviertel.ch utilise des cookies de session qui ne sont actifs que tant que le navigateur Internet est ouvert. Les cookies sont des fichiers texte qui sont d\u00e9pos\u00e9s et stock\u00e9s sur un syst\u00e8me informatique via un navigateur Internet.<\/span><\/p><p><span style=\"font-weight: 400;\">Les cookies peuvent \u00eatre utilis\u00e9s pour optimiser les informations et les offres du site web d'Aktion Vierviertel au profit des utilisateurs. Les cookies permettent de reconna\u00eetre un utilisateur. Le but de cette reconnaissance est de faciliter l'utilisation de notre site web par l'utilisateur. Aucune donn\u00e9e personnelle n'est collect\u00e9e au moyen de cookies.<\/span><\/p><p><span style=\"font-weight: 400;\">Si vous choisissez de ne pas d\u00e9sactiver les cookies, vous acceptez l'utilisation des cookies par www.aktionvierviertel.ch.<\/span><\/p><p><span style=\"font-weight: 400;\">L'utilisateur peut \u00e0 tout moment emp\u00eacher la mise en place de cookies par notre site Internet au moyen d'un r\u00e9glage appropri\u00e9 du navigateur Internet utilis\u00e9 et s'opposer ainsi de mani\u00e8re permanente \u00e0 la mise en place de cookies. Les cookies qui ont d\u00e9j\u00e0 \u00e9t\u00e9 d\u00e9finis peuvent \u00eatre supprim\u00e9s \u00e0 tout moment par le biais d'un navigateur Internet ou d'autres logiciels.<\/span><\/p><p><span style=\"font-weight: 400;\">Le site www.aktionvierviertel.ch peut ne pas fonctionner correctement sans cookies.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1303\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1303\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">3. Collecte de donn\u00e9es et d'informations g\u00e9n\u00e9rales<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1303\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1303\"><p><span style=\"font-weight: 400;\">Le site web www.aktionvierviertel.ch collecte une s\u00e9rie de donn\u00e9es et d'informations g\u00e9n\u00e9rales chaque fois qu'un utilisateur ou un syst\u00e8me automatis\u00e9 appelle le site web. Ces donn\u00e9es et informations g\u00e9n\u00e9rales sont stock\u00e9es dans les fichiers journaux du serveur. Peuvent \u00eatre enregistr\u00e9s : les types et versions de navigateurs utilis\u00e9s ; le syst\u00e8me d'exploitation utilis\u00e9 par le syst\u00e8me d'acc\u00e8s ; le site web \u00e0 partir duquel un syst\u00e8me d'acc\u00e8s acc\u00e8de au site web ; les sous-sites web auxquels un syst\u00e8me d'acc\u00e8s acc\u00e8de sur le site web ; la date et l'heure d'un acc\u00e8s au site web ; une adresse de protocole Internet (adresse IP) ; le fournisseur de services Internet (ISP) du syst\u00e8me d'acc\u00e8s ; d'autres donn\u00e9es et informations similaires qui servent \u00e0 pr\u00e9venir le danger en cas d'attaques sur les syst\u00e8mes informatiques.<\/span><\/p><p><span style=\"font-weight: 400;\">Ces donn\u00e9es et informations sont collect\u00e9es de mani\u00e8re anonyme. En utilisant ces donn\u00e9es et informations, Aktion Vierviertel ne tire aucune conclusion sur les utilisateurs. Ces informations sont plut\u00f4t n\u00e9cessaires pour fournir correctement le contenu du site web, pour optimiser le contenu du site web et la publicit\u00e9, pour assurer la fonctionnalit\u00e9 \u00e0 long terme des syst\u00e8mes informatiques et de la technologie du site web, et pour fournir aux autorit\u00e9s charg\u00e9es de l'application de la loi les informations n\u00e9cessaires \u00e0 des poursuites en cas de cyberattaque.<\/span><\/p><p><span style=\"font-weight: 400;\">Les donn\u00e9es anonymes des fichiers journaux du serveur sont stock\u00e9es s\u00e9par\u00e9ment de toutes les donn\u00e9es personnelles fournies par un-e utilisatrice\/teur.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1304\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1304\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">4. Collecte de donn\u00e9es personnelles<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1304\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1304\"><p><span style=\"font-weight: 400;\">L'utilisatrice\/eur a la possibilit\u00e9 de s'inscrire sur le site www.aktionvierviertel.ch en fournissant des donn\u00e9es personnelles. L'enregistrement est n\u00e9cessaire, entre autres, pour s'abonner aux bulletins d'information ou pour soumettre le formulaire de contact, pour signer des actions en ligne telles que des appels ou des p\u00e9titions, pour s'enregistrer en tant que membre actif d'Aktion Vierviertel, pour commander du mat\u00e9riel de campagne, pour devenir membre d'Aktion Vierviertel ou pour soutenir financi\u00e8rement Aktion Vierviertel en faisant un don ou en achetant un article de marchandise.<\/span><\/p><p><span style=\"font-weight: 400;\">Les donn\u00e9es personnelles qui sont transmises \u00e0 Aktion Vierviertel dans le cadre de ce processus sont indiqu\u00e9es dans le masque de saisie utilis\u00e9 pour l'enregistrement.<\/span><\/p><p><span style=\"font-weight: 400;\">Les donn\u00e9es personnelles saisies par l'utilisatrice\/eur sont collect\u00e9es et stock\u00e9es exclusivement pour nos propres besoins.<\/span><\/p><p><span style=\"font-weight: 400;\">En s'inscrivant, l'utilisatrice\/eur d\u00e9clare l'exactitude de ses donn\u00e9es personnelles.<\/span><\/p><p><span style=\"font-weight: 400;\">En s'inscrivant sur le site www. aktionvierviertel.ch, l'adresse IP attribu\u00e9e par le fournisseur d'acc\u00e8s \u00e0 Internet (FAI) de l'utilisatrice\/eur, la date et l'heure de l'inscription sont \u00e9galement enregistr\u00e9es. Le stockage de ces donn\u00e9es a lieu dans la mesure o\u00f9 ce n'est que de cette mani\u00e8re que l'on peut emp\u00eacher l'utilisation abusive des services et, si n\u00e9cessaire, ces donn\u00e9es permettent d'\u00e9lucider les infractions p\u00e9nales commises. En principe, ces donn\u00e9es ne sont pas transmises \u00e0 des tiers, sauf s'il existe une obligation l\u00e9gale de les transmettre ou si la transmission sert \u00e0 des fins de poursuites p\u00e9nales.<\/span><\/p><p><span style=\"font-weight: 400;\">L'enregistrement des utilisatrices\/eurs en fournissant volontairement des donn\u00e9es personnelles sert \u00e0 Aktion Vierviertel pour offrir \u00e0 l'utilisateur des contenus ou des services qui, en raison de la nature de la mati\u00e8re, ne peuvent \u00eatre offerts qu'aux utilisatrices\/eurs enregistr\u00e9s. Les utilisatrice\/eurs enregistr\u00e9-e-s ont la possibilit\u00e9 de modifier les donn\u00e9es personnelles fournies lors de l'enregistrement ou de les faire supprimer compl\u00e8tement de la base de donn\u00e9es de Aktion Vierviertel.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1305\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-1305\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">5. Utilisation de processeurs<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1305\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-1305\"><p><span style=\"font-weight: 400;\">\u00c0 des fins de traitement, Aktion Vierviertel peut organiser le transfert \u00e0 des processeurs qui utilisent \u00e9galement les donn\u00e9es personnelles exclusivement pour un usage interne imputable \u00e0 Aktion Vierviertel.<\/span><\/p><p><span style=\"font-weight: 400;\">Nos sous-traitants suivants traitent des donn\u00e9es personnelles dans des pays tiers (hors de la Suisse et de l'Union europ\u00e9enne) :<\/span><\/p><h3><b>(a) envoi de courriel par Mailchimp<\/b><\/h3><p class=\"translation-block\">par le biais du prestataire de services d'envoi \"MailChimp\", une plateforme d'envoi de newsletter du prestataire am\u00e9ricain Rocket Science Group, LLC, 675 Ponce De Leon Ave NE #5000, Atlanta, GA 30308, USA. Vous pouvez consulter la politique de confidentialit\u00e9 du fournisseur de services de mailing \u00e0 l'adresse suivante : https:\/\/mailchimp.com\/legal\/privacy\/. The Rocket Science Group LLC d\/b\/a MailChimp est certifi\u00e9 dans le cadre de l'accord Privacy Shield et offre ainsi une garantie de conformit\u00e9 au niveau europ\u00e9en de protection des donn\u00e9es (https:\/\/www.privacyshield.gov\/participant?id=a2zt0000000TO6hAAG&amp;status=Active). Le prestataire de services d'exp\u00e9dition est utilis\u00e9 sur la base de nos int\u00e9r\u00eats l\u00e9gitimes conform\u00e9ment \u00e0 l'article 6, paragraphe 1, lettre f. du RGPD et un accord de traitement des commandes conform\u00e9ment \u00e0 l'article 28, paragraphe 3, point 1 du RGPD.<\/p><p><span style=\"font-weight: 400;\">Le prestataire de services d'envoi peut utiliser les donn\u00e9es des destinataires sous forme pseudonyme, c'est-\u00e0-dire sans les attribuer \u00e0 un-e utilisatrice\/eur, pour optimiser ou am\u00e9liorer ses propres services, par exemple pour optimiser techniquement l'envoi et la pr\u00e9sentation de la newsletter ou \u00e0 des fins statistiques. Toutefois, le prestataire de services d'envoi n'utilise pas les donn\u00e9es des destinataires de notre newsletter pour leur \u00e9crire lui-m\u00eame ou pour transmettre les donn\u00e9es \u00e0 des tiers.<\/span><\/p><h3><b>b) Paiement par carte de cr\u00e9dit via Payrexx<\/b><\/h3><p class=\"translation-block\">Si l'utilisatrice\/eur d\u00e9cide de payer par carte de cr\u00e9dit lors d'un processus de paiement sur le site www.aktionvierviertel.ch, cela se fera en utilisant Payrexx, un service de la soci\u00e9t\u00e9 Payrexx AG. Burgstrasse 18, 3600 Thoune, Suisse (\"Payrexx\"). Payrexx utilise, entre autres, des cookies qui sont stock\u00e9s sur l'ordinateur de l'utilisateur et qui permettent une analyse de l'utilisation du site web. Au cours de l'utilisation, des donn\u00e9es, telles que notamment l'adresse IP et les activit\u00e9s de l'utilisateur, peuvent \u00eatre transmises \u00e0 un serveur de Payrexx et y \u00eatre stock\u00e9es. Payrexx peut transf\u00e9rer ces informations \u00e0 des tiers si cela est requis par la loi ou si le traitement de ces donn\u00e9es par des tiers a lieu. L'utilisatrice\/eur peut emp\u00eacher la collecte et la transmission de donn\u00e9es personnelles (en particulier l'adresse IP de l'utilisateur) ainsi que le traitement de ces donn\u00e9es en d\u00e9sactivant l'ex\u00e9cution du script Java dans son navigateur, par exemple avec le bloqueur de script NoScript. Une option d'exclusion est disponible ici. Vous trouverez de plus amples informations sur Payrexx ici.<\/p><h3><b>c) Analyse du site web avec Google Analytics<\/b><\/h3><p class=\"translation-block\">Aktion Vierviertel utilise le service d'analyse Google Analytics de Google, Inc. 1600 Amphitheatre Parkway, Mountain View, CA 94043, USA (\"Google\") sur le site Internet www. aktionvierviertel.ch. Google utilise la technologie des cookies pour fournir ce service. Les informations g\u00e9n\u00e9r\u00e9es par le cookie concernant l'utilisation du site par l'utilisatrice\/eur seront transmises \u00e0 Google et stock\u00e9es sur des serveurs situ\u00e9s aux \u00c9tats-Unis. Google utilisera ces informations pour compiler des rapports sur l'activit\u00e9 du site Web pour Aktion Vierviertel et pour fournir d'autres services li\u00e9s \u00e0 l'activit\u00e9 du site Web. Google peut \u00e9galement transmettre ces informations \u00e0 des tiers si la loi l'exige ou si ces tiers traitent ces informations pour le compte de Google. L'adresse IP transmise par le navigateur de l'utilisatrice\/eur dans le cadre de Google Analytics ne sera pas fusionn\u00e9e avec d'autres donn\u00e9es de Google. L'utilisatrice\/eur peut emp\u00eacher le stockage des cookies en effectuant les r\u00e9glages appropri\u00e9s dans le logiciel de navigation. En outre, l'utilisatrice\/eur peut s'opposer \u00e0 la collecte et \u00e0 l'utilisation par Google des donn\u00e9es g\u00e9n\u00e9r\u00e9es par les cookies et li\u00e9es \u00e0 son utilisation du site (y compris l'adresse IP) et emp\u00eacher le traitement de ces donn\u00e9es par Google en t\u00e9l\u00e9chargeant et en installant le plugin de navigateur suivant ici. Cela placera un cookie de d\u00e9sactivation sur l'appareil de l'utilisateur. Si l'utilisateur supprime les cookies ou change de navigateur, il doit cliquer \u00e0 nouveau sur ce lien. Vous trouverez de plus amples informations sur Google Analytics ici et ici.<\/p><h3><b>d) Plugins sociaux de Facebook, Instagram, Twitter et YouTube<\/b><\/h3><p><span style=\"font-weight: 400;\">Aktion Vierviertel utilise des plugins dits sociaux des r\u00e9seaux sociaux Facebook, Instagram, Twitter et YouTube sur son site web www.aktionvierviertel.ch.<\/span><\/p><p class=\"translation-block\">Facebook et Instagram sont exploit\u00e9s par Facebook, Inc, 1601 S. California Ave, Palo Alto, CA 94304, \u00c9tats-Unis (\"Facebook\" et \"Instagram\"). Vous trouverez un aper\u00e7u des plugins Facebook et Instagram et de leur apparence ici et ici.<\/p><p class=\"translation-block\">Twitter est exploit\u00e9 par Twitter, Inc. 1355 Market Street, Suite 900, San Francisco, CA 94103, USA (\"Twitter\"). Un aper\u00e7u des plugins Twitter et de leur apparence peut \u00eatre trouv\u00e9 ici.<\/p><p class=\"translation-block\">Youtube est exploit\u00e9e par YouTube, LLC, 901 Cherry Avenue, San Bruno, CA 94066, USA (\"Youtube\"). Un aper\u00e7u des plugins Youtube et de leur apparence peut \u00eatre trouv\u00e9 ici.<\/p><p><span style=\"font-weight: 400;\">Lorsque l'utilisatrice\/eur appelle une page de notre site web qui contient un tel plugin, le navigateur \u00e9tablit une connexion directe avec les serveurs de Facebook, Instagram, Twitter et Youtube. Le contenu du plugin est transmis directement au navigateur de l'utilisateur par le fournisseur respectif et int\u00e9gr\u00e9 au site web. En int\u00e9grant les plugins, les fournisseurs re\u00e7oivent l'information que l'utilisatrice\/eur a appel\u00e9 la page correspondante du site web avec son navigateur, m\u00eame si elle ou il n'a pas de profil ou n'est pas actuellement connect\u00e9-e. Ces informations (y compris l'adresse IP) sont transmises par le navigateur de l'utilisateur directement \u00e0 un serveur du fournisseur concern\u00e9 et y sont stock\u00e9es.<\/span><\/p><p><span style=\"font-weight: 400;\">Si l'utilisatrice\/eur est connect\u00e9 \u00e0 l'un des services, les prestataires peuvent attribuer directement la visite du site web d'Aktion Vierviertel au profil de l'utilisateur sur Facebook, Instagram, Twitter ou YouTube. Si l'utilisatrice\/eur interagit avec les plugins, par exemple en cliquant sur le bouton \"J'aime\" de Facebook, les informations correspondantes sont \u00e9galement transmises directement \u00e0 un serveur des fournisseurs et y sont stock\u00e9es. Les informations peuvent \u00e9galement \u00eatre publi\u00e9es sur le r\u00e9seau social apr\u00e8s le consentement de l'utilisatrice\/eur et y \u00eatre affich\u00e9es aux contacts.<\/span><\/p><p class=\"translation-block\">L'objectif et l'\u00e9tendue de la collecte des donn\u00e9es ainsi que le traitement ult\u00e9rieur et l'utilisation des donn\u00e9es par les prestataires, ainsi que les droits et les possibilit\u00e9s de param\u00e9trage de l'utilisateur \u00e0 cet \u00e9gard pour la protection de la vie priv\u00e9e, figurent dans les avis de protection des donn\u00e9es des prestataires (Facebook, Instagram, Twitter, YouTube).<\/p><p class=\"translation-block\">Si l'utilisatrice\/eur ne souhaite pas que Facebook, Instagram, Twitter ou Youtube attribue directement les donn\u00e9es collect\u00e9es via le site web de Aktion Vierviertel au profil de l'utilisateur dans le service respectif, les utilisateurs doivent se d\u00e9connecter du service correspondant avant de visiter le site web. Les utilisateurs peuvent \u00e9galement emp\u00eacher compl\u00e8tement le chargement des plugins \u00e0 l'aide de modules compl\u00e9mentaires de navigateur, par exemple avec le bloqueur de script NoScript.<\/p><h3><b>e) Pixel Facebook<\/b><\/h3><p class=\"translation-block\">Aktion Vierviertel utilise le pixel d'action du visiteur de Facebook, Inc, 1601 S. California Ave, Palo Alto, CA 94304, USA (\"Facebook\") sur le site web www.aktionvierviertel.ch pour mesurer les conversions. Cela permet de suivre le comportement de l'utilisatrice\/eur apr\u00e8s qu'il ait \u00e9t\u00e9 redirig\u00e9 vers le site web de Aktion Vierviertel en cliquant sur une publicit\u00e9 Facebook. Cela permet d'\u00e9valuer l'efficacit\u00e9 des publicit\u00e9s Facebook \u00e0 des fins statistiques et d'\u00e9tudes de march\u00e9 et d'optimiser les futures mesures publicitaires. Les donn\u00e9es collect\u00e9es sont anonymes pour Aktion Vierviertel, aucune conclusion ne peut \u00eatre tir\u00e9e sur l'identit\u00e9 des utilisatrices\/eurs. Cependant, les donn\u00e9es sont stock\u00e9es et trait\u00e9es par Facebook afin qu'une connexion au profil d'utilisatrice\/eur respective\/f soit possible et que Facebook puisse utiliser les donn\u00e9es \u00e0 ses propres fins publicitaires, conform\u00e9ment \u00e0 la politique d'utilisation des donn\u00e9es de Facebook. Cela permet \u00e0 Facebook d'afficher des publicit\u00e9s sur les pages Facebook ainsi qu'en dehors de Facebook. Cette utilisation des donn\u00e9es ne peut pas \u00eatre influenc\u00e9e par nous, l'exploitant du site. L'utilisatrice\/eur peut d\u00e9sactiver la fonction de remarketing \"Custom Audiences\" dans la section des param\u00e8tres des publicit\u00e9s ici. Pour ce faire, l'utilisatrice\/eur doit \u00eatre connect\u00e9-e \u00e0 Facebook.<\/p><p class=\"translation-block\">Si l'utilisatrice\/eur ne poss\u00e8de pas de compte Facebook, elle\/il peut d\u00e9sactiver la publicit\u00e9 bas\u00e9e sur l'utilisation de Facebook sur le site web de l'Alliance europ\u00e9enne pour la publicit\u00e9 num\u00e9rique interactive ici. De plus amples informations sur Facebook sont disponibles ici.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1306\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-1306\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">6. Comment nous contacter via le site Internet<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1306\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-1306\"><p><span style=\"font-weight: 400;\">Le site web www.aktionvierviertel.ch contient une option de contact \u00e9lectronique rapide. Si un-e utilisatrice\/eur contacte Aktion Vierviertel par e-mail ou via un formulaire de contact, les donn\u00e9es personnelles transmises par elle\/lui sont automatiquement stock\u00e9es.<\/span><\/p><p><span style=\"font-weight: 400;\">Ces donn\u00e9es personnelles transmises \u00e0 Aktion Vierviertel par un-e utilisatrice\/eur sur une base volontaire sont stock\u00e9es dans le but de traiter ou de contacter l'utilisatrice\/eur. Ces donn\u00e9es personnelles ne sont pas transmises \u00e0 des tiers.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1307\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-1307\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">7. Suppression et blocage de routine des donn\u00e9es personnelles<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1307\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-1307\"><p><span style=\"font-weight: 400;\">Aktion Vierviertel traite et stocke les donn\u00e9es personnelles des utilisatrices\/eurs uniquement pour la dur\u00e9e n\u00e9cessaire \u00e0 la r\u00e9alisation de l'objectif du stockage ou si cela est pr\u00e9vu par les exigences l\u00e9gales auxquelles Aktion Vierviertel est soumise.<\/span><\/p><p><span style=\"font-weight: 400;\">Si la finalit\u00e9 du stockage cesse de s'appliquer ou si une p\u00e9riode de stockage fix\u00e9e par la loi expire, les donn\u00e9es personnelles seront syst\u00e9matiquement bloqu\u00e9es ou supprim\u00e9es conform\u00e9ment aux dispositions l\u00e9gales.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1308\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-1308\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">8. Base l\u00e9gale du traitement des donn\u00e9es<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1308\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-1308\"><p><span style=\"font-weight: 400;\">Aucune donn\u00e9e n'est trait\u00e9e sans base l\u00e9gale. Les \u00e9l\u00e9ments suivants servent de fondement juridique:<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">le consentement (pour la finalit\u00e9 respective, l'utilisation des donn\u00e9es r\u00e9guli\u00e8res des utilisatrices\/eurs et pour le transfert des donn\u00e9es vers des pays tiers),<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">l'ex\u00e9cution d'un contrat ou de mesures pr\u00e9contractuelles,<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">des obligations l\u00e9gales ou la protection des int\u00e9r\u00eats vitaux de la personne concern\u00e9e ou d'une autre personne physique, et<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">la protection d'un int\u00e9r\u00eat l\u00e9gitime d'Aktion Vierviertel (par exemple, les int\u00e9r\u00eats \u00e9conomiques) ou d'un tiers.<\/span><\/li><\/ul><p><span style=\"font-weight: 400;\">conform\u00e9ment \u00e0 la loi suisse sur la protection des donn\u00e9es LPD ou \u00e0 l'article 6 du r\u00e8glement g\u00e9n\u00e9ral sur la protection des donn\u00e9es.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1309\" class=\"elementor-tab-title\" data-tab=\"9\" role=\"button\" aria-controls=\"elementor-tab-content-1309\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">9. Droits des utilisatrices\/eurs<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1309\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"9\" role=\"region\" aria-labelledby=\"elementor-tab-title-1309\"><h3><b>a) Droit \u00e0 la confirmation<\/b><\/h3><p><span style=\"font-weight: 400;\">Tout-e utilisatrice\/eur a le droit de demander \u00e0 Aktion Vierviertel la confirmation que les donn\u00e9es personnelles en question sont trait\u00e9es. Si un-e utilisatrice\/eur souhaite exercer ce droit de confirmation, elle\/il peut \u00e0 tout moment contacter Aktion Vierviertel.<\/span><\/p><h3><b>b) Droit \u00e0 l'information<\/b><\/h3><p><span style=\"font-weight: 400;\">Tout-e utilisatrice\/eur concern\u00e9-e par le traitement de donn\u00e9es personnelles a le droit de recevoir \u00e0 tout moment de la part de l'Aktion Vierviertel des informations gratuites sur les donn\u00e9es personnelles stock\u00e9es \u00e0 son sujet ainsi qu'une copie de ces informations. Des informations sont fournies sur :<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">les finalit\u00e9s du traitement,<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">les cat\u00e9gories de donn\u00e9es personnelles trait\u00e9es,<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">les destinataires ou cat\u00e9gories de destinataires auxquel-le-s les donn\u00e9es \u00e0 caract\u00e8re personnel ont \u00e9t\u00e9 ou seront divulgu\u00e9es,<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">si des donn\u00e9es \u00e0 caract\u00e8re personnel ont \u00e9t\u00e9 transf\u00e9r\u00e9es \u00e0 un pays tiers ou \u00e0 une organisation internationale et, dans l'affirmative, si des garanties appropri\u00e9es sont en place en ce qui concerne le transfert,<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">la p\u00e9riode de stockage pr\u00e9vue ou, si cela n'est pas possible, les crit\u00e8res permettant de d\u00e9terminer cette p\u00e9riode,<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">l'existence d'un droit de rectification ou d'effacement des donn\u00e9es \u00e0 caract\u00e8re personnel la\/le concernant ou de limitation du traitement par Aktion Vierviertel ou l'existence d'un droit d'opposition \u00e0 un tel traitement,<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">l'existence d'un droit de recours aupr\u00e8s d'une autorit\u00e9 de contr\u00f4le,<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">l'origine des donn\u00e9es personnelles si elles ne sont pas collect\u00e9es aupr\u00e8s de l'utilisatrice\/eur,<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">l'existence d'une prise de d\u00e9cision automatis\u00e9e, y compris le profilage et des informations significatives sur la logique impliqu\u00e9e, ainsi que la port\u00e9e et les effets pr\u00e9vus de ce traitement pour les utilisatrices\/eurs.<\/span><\/li><\/ul><p><span style=\"font-weight: 400;\">Si un-e utilisatrice\/eur souhaite exercer ce droit \u00e0 l'information, elle\/il peut \u00e0 tout moment contacter Aktion Vierviertel.<\/span><\/p><h3><b>c) Droit de rectification<\/b><\/h3><p><span style=\"font-weight: 400;\">Tout-e utilisatrice\/eur concern\u00e9-e par le traitement de donn\u00e9es \u00e0 caract\u00e8re personnel a le droit d'exiger la rectification imm\u00e9diate de donn\u00e9es \u00e0 caract\u00e8re personnel inexactes et, compte tenu des finalit\u00e9s du traitement, de compl\u00e9ter des donn\u00e9es \u00e0 caract\u00e8re personnel incompl\u00e8tes.<\/span><\/p><p><span style=\"font-weight: 400;\">Si un-e utilisatrice\/eur souhaite exercer ce droit de rectification, elle\/il peut \u00e0 tout moment contacter Aktion Vierviertel.<\/span><\/p><h3><b>d) Droit \u00e0 l'effacement (droit \u00e0 l'oubli)<\/b><\/h3><p><span style=\"font-weight: 400;\">Tout-e utilisatrice\/eur concern\u00e9-e par le traitement de donn\u00e9es \u00e0 caract\u00e8re personnel a le droit d'exiger de Aktion Vierviertel que les donn\u00e9es \u00e0 caract\u00e8re personnel le concernant soient imm\u00e9diatement effac\u00e9es, \u00e0 condition qu'une des raisons suivantes s'applique et dans la mesure o\u00f9 le traitement n'est pas n\u00e9cessaire :<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Les donn\u00e9es \u00e0 caract\u00e8re personnel ont \u00e9t\u00e9 collect\u00e9es ou autrement trait\u00e9es \u00e0 des fins pour lesquelles elles ne sont plus n\u00e9cessaires.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">L'utilisatrice\/eur retire le consentement sur lequel le traitement \u00e9tait fond\u00e9 et il n'existe aucune autre base juridique pour le traitement.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">L'utilisice\/ateur s'oppose au traitement et il n'existe pas de motifs l\u00e9gitimes pr\u00e9pond\u00e9rants pour le traitement.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">L'effacement des donn\u00e9es personnelles est n\u00e9cessaire pour le respect d'une obligation l\u00e9gale.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Les donn\u00e9es personnelles appartiennent \u00e0 un-e enfant qui n'a pas encore atteint l'\u00e2ge de 16 ans ou pour la\/equel il n'y a pas de consentement de la\/du titulaire de l'autorit\u00e9 parentale.<\/span><\/li><\/ul><p><span style=\"font-weight: 400;\">Si l'une des raisons susmentionn\u00e9es s'applique et qu'un-e utilisatrice\/eur souhaite obtenir la suppression des donn\u00e9es personnelles stock\u00e9es par Aktion Vierviertel, elle\/il peut, \u00e0 tout moment, contacter Aktion Vierviertel.<\/span><\/p><p><span style=\"font-weight: 400;\">Si les donn\u00e9es \u00e0 caract\u00e8re personnel ont \u00e9t\u00e9 rendues publiques par l'Aktion Vierviertel et qu'Aktion Vierviertel est oblig\u00e9e d'effacer les donn\u00e9es \u00e0 caract\u00e8re personnel, Aktion Vierviertel prend des mesures raisonnables, y compris des mesures techniques, eu \u00e9gard \u00e0 la technologie disponible et au co\u00fbt de mise en \u0153uvre, pour informer les autres responsables du traitement des donn\u00e9es \u00e0 caract\u00e8re personnel publi\u00e9es, que l'utilisatrice\/eur a demand\u00e9 \u00e0 cet autre responsable du traitement l'effacement de tous les liens vers les donn\u00e9es \u00e0 caract\u00e8re personnel ou des copies ou r\u00e9plications des donn\u00e9es \u00e0 caract\u00e8re personnel, sauf si le traitement est n\u00e9cessaire.<\/span><\/p><h3><b>e) Droit de restreindre le traitement<\/b><\/h3><p><span style=\"font-weight: 400;\">Tout-e utilisatrice\/eur concern\u00e9-e par le traitement de ses donn\u00e9es personnelles a le droit d'obtenir de Aktion Vierviertel la limitation du traitement si l'une des conditions suivantes est remplie :<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">L'exactitude des donn\u00e9es personnelles est contest\u00e9e par l'utilisatrice\/eur pendant une p\u00e9riode permettant \u00e0 Aktion Vierviertel de v\u00e9rifier l'exactitude des donn\u00e9es personnelles.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Le traitement est ill\u00e9gal, l'utilisatrice\/eur s'oppose \u00e0 l'effacement des donn\u00e9es personnelles et demande \u00e0 la place la restriction de l'utilisation des donn\u00e9es personnelles.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Aktion Vierviertel n'a plus besoin des donn\u00e9es personnelles aux fins du traitement, mais l'utilisatrice\/eur en a besoin pour faire valoir, exercer ou d\u00e9fendre des droits l\u00e9gaux.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">L'utilisatrice\/eur s'est oppos\u00e9 au traitement et il n'est pas encore clair si les motifs l\u00e9gitimes de Aktion Vierviertel l'emportent sur ceux de l'utilisatrice\/eur.<\/span><\/li><\/ul><p><span style=\"font-weight: 400;\">Si l'une des conditions susmentionn\u00e9es est remplie, et si un-e utilisatrice\/eur souhaite demander la restriction des donn\u00e9es personnelles stock\u00e9es par l'Aktion Vierviertel, elle\/il peut, \u00e0 tout moment, contacter Aktion Vierviertel.<\/span><\/p><h3><b>f) Droit \u00e0 la portabilit\u00e9 des donn\u00e9es<\/b><\/h3><p><span style=\"font-weight: 400;\">Tout-e utilisatrice\/eur concern\u00e9 par le traitement de donn\u00e9es personnelles a le droit de recevoir les donn\u00e9es personnelles le concernant, qui ont \u00e9t\u00e9 fournies par les utilisatrice\/eurs \u00e0 Aktion Vierviertel, dans un format structur\u00e9, commun et lisible par machine.<\/span><\/p><p><span style=\"font-weight: 400;\">Elle\/Il a \u00e9galement le droit de transmettre ces donn\u00e9es \u00e0 un autre processeur de donn\u00e9es sans qu'Aktion Vierviertel \u00e0 qui les donn\u00e9es personnelles ont \u00e9t\u00e9 fournies n'y fasse obstacle, \u00e0 condition que le traitement soit bas\u00e9 sur le consentement ou sur un contrat et que le traitement soit effectu\u00e9 \u00e0 l'aide de proc\u00e9dures automatis\u00e9es, \u00e0 moins que le traitement ne soit n\u00e9cessaire \u00e0 l'ex\u00e9cution d'une t\u00e2che effectu\u00e9e dans l'int\u00e9r\u00eat public ou dans l'exercice de l'autorit\u00e9 officielle dont est investie Aktion Vierviertel.<\/span><\/p><p><span style=\"font-weight: 400;\">En outre, l'utilisatrice\/eur peut demander que les donn\u00e9es \u00e0 caract\u00e8re personnel soient transf\u00e9r\u00e9es directement d'un processeur de donn\u00e9es \u00e0 un autre processeur de donn\u00e9es, dans la mesure o\u00f9 cela est techniquement possible et dans la mesure o\u00f9 cela ne porte pas atteinte aux droits et libert\u00e9s d'autres personnes.<\/span><\/p><p><span style=\"font-weight: 400;\">Afin de faire valoir le droit \u00e0 la portabilit\u00e9 des donn\u00e9es, l'utilisatrice\/eur peut \u00e0 tout moment contacter Aktion Vierviertel.<\/span><\/p><h3><b>g) Droit d'opposition<\/b><\/h3><p><span style=\"font-weight: 400;\">Tout-e utilisatrice\/eur concern\u00e9-e par le traitement de donn\u00e9es personnelles a le droit de s'opposer \u00e0 tout moment au traitement des donn\u00e9es personnelles le concernant. Cela s'applique \u00e9galement au profilage fond\u00e9 sur ces dispositions.<\/span><\/p><p><span style=\"font-weight: 400;\">Aktion Vierviertel ne traitera plus les donn\u00e9es \u00e0 caract\u00e8re personnel en cas d'opposition, \u00e0 moins que des motifs l\u00e9gitimes imp\u00e9rieux pour le traitement puissent \u00eatre d\u00e9montr\u00e9s, qui pr\u00e9valent sur les int\u00e9r\u00eats, les droits et les libert\u00e9s de l'utilisateur, ou que le traitement serve \u00e0 faire valoir, exercer ou d\u00e9fendre des droits en justice.<\/span><\/p><p><span style=\"font-weight: 400;\">Si Aktion Vierviertel traite des donn\u00e9es personnelles \u00e0 des fins de marketing direct, l'utilisatrice\/eur a le droit de s'opposer \u00e0 ce traitement \u00e0 tout moment. Si l'utilisatrice\/eur s'oppose \u00e0 Aktion Vierviertel au traitement \u00e0 des fins de marketing direct, Aktion Vierviertel ne traitera plus les donn\u00e9es personnelles \u00e0 ces fins.<\/span><\/p><p><span style=\"font-weight: 400;\">Pour exercer son droit d'opposition, l'utilisatrice\/eur peut s'adresser directement \u00e0 Aktion Vierviertel.<\/span><\/p><h3><b>h) D\u00e9cisions automatis\u00e9es dans des cas individuels, y compris le profilage.<\/b><\/h3><p><span style=\"font-weight: 400;\">Tout-e utilisatrice\/eur concern\u00e9-e par le traitement de donn\u00e9es \u00e0 caract\u00e8re personnel a le droit de ne pas faire l'objet d'une d\u00e9cision fond\u00e9e uniquement sur un traitement automatis\u00e9, y compris le profilage, qui produit des effets juridiques le concernant ou l'affecte de mani\u00e8re significative de fa\u00e7on similaire, \u00e0 moins que la d\u00e9cision<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">soit n\u00e9cessaire pour la conclusion ou l'ex\u00e9cution d'un contrat entre l'utilisatrice\/eur et Aktion Vierviertel ; ou<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">soit faite avec le consentement explicite de l'utilisatrice\/eur.<\/span><\/li><\/ul><p><span style=\"font-weight: 400;\">Si la d\u00e9cision est n\u00e9cessaire pour la conclusion ou l'ex\u00e9cution d'un contrat entre l'utilisatrice\/eur et Aktion Vierviertel, ou si elle est prise avec le consentement explicite de l'utilisateur, Aktion Vierviertel prendra des mesures raisonnables pour prot\u00e9ger les droits et libert\u00e9s de l'utilisatrice\/eur et ses int\u00e9r\u00eats l\u00e9gitimes, y compris au moins le droit de s'opposer \u00e0 l'interaction personnelle avec Aktion Vierviertel, d'exprimer son point de vue et de contester la d\u00e9cision.<\/span><\/p><p><span style=\"font-weight: 400;\">Si l'utilisatrice\/eur souhaite exercer ses droits concernant les d\u00e9cisions automatis\u00e9es,elle\/ il peut, \u00e0 tout moment, s'adresser \u00e0 Aktion Vierviertel.<\/span><\/p><h3><b>i) Droit de retirer le consentement en vertu de la loi sur la protection des donn\u00e9es<\/b><\/h3><p><span style=\"font-weight: 400;\">Tout-e utilisatrice\/eur concern\u00e9-e par le traitement des donn\u00e9es personnelles a le droit de r\u00e9voquer \u00e0 tout moment son consentement au traitement des donn\u00e9es personnelles.<\/span><\/p><p><span style=\"font-weight: 400;\">Si l'utilisatrice\/eur souhaite exercer son droit de retirer son consentement, elle\/il peut \u00e0 tout moment contacter Aktion Vierviertel.<\/span><\/p><h3><b>j) Droit de d\u00e9poser une plainte aupr\u00e8s d'une autorit\u00e9 de surveillance<\/b><\/h3><p><span style=\"font-weight: 400;\">Tout-e utilisatrice\/eur concern\u00e9-e par le traitement de ses donn\u00e9es personnelles a le droit de d\u00e9poser une plainte aupr\u00e8s de l'autorit\u00e9 de contr\u00f4le locale charg\u00e9e de la protection des donn\u00e9es concernant les violations de la protection des donn\u00e9es par Aktion Vierviertel.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-13010\" class=\"elementor-tab-title\" data-tab=\"10\" role=\"button\" aria-controls=\"elementor-tab-content-13010\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">10. Divers<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-13010\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"10\" role=\"region\" aria-labelledby=\"elementor-tab-title-13010\"><p><span style=\"font-weight: 400;\">Nous tenons \u00e0 vous informer que le stockage et la mise \u00e0 disposition de donn\u00e9es personnelles sont en partie requis par la loi (par exemple, en raison des r\u00e9glementations fiscales) ou peuvent \u00e9galement r\u00e9sulter de r\u00e9glementations contractuelles (par exemple, pour des informations sur le partenaire contractuel). Parfois, afin de conclure un contrat, il peut \u00eatre n\u00e9cessaire qu'un-e utilisatrice\/eur fournisse \u00e0 Aktion Vierviertel des donn\u00e9es personnelles qui doivent ensuite \u00eatre trait\u00e9es par Aktion Vierviertel. Par exemple, l'utilisatrice\/eur est oblig\u00e9-e de fournir \u00e0 Aktion Vierviertel des donn\u00e9es personnelles si Aktion Vierviertel conclut un contrat avec l'utilisatrice\/eur. Le fait de ne pas fournir les donn\u00e9es personnelles signifierait que le contrat avec l'utilisatrice\/eur ne pourrait \u00eatre conclu.<\/span><\/p><p><span style=\"font-weight: 400;\">Le site web www.aktionvierviertel.ch renvoie \u00e0 d'autres sites web dont Aktion Vierviertel n'est pas responsable du contenu.<\/span><\/p><p><span style=\"font-weight: 400;\">Aktion Vierviertel peut modifier, compl\u00e9ter ou remplacer les dispositions de la pr\u00e9sente d\u00e9claration de protection des donn\u00e9es, en tout ou en partie, \u00e0 tout moment et sans pr\u00e9avis. La version de la pr\u00e9sente d\u00e9claration de protection des donn\u00e9es en vigueur au moment de la visite du site web www.aktionvierviertel.ch s'applique.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f1dc097 ae-bg-gallery-type-default\" data-id=\"f1dc097\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Datenschutzrichtlinie AKTION VIERVIERTEL, mit Sitz in 8000 Z\u00fcrich, erfasst, verarbeitet, speichert und sch\u00fctzt die Daten von Personen, die auf die Website www.aktionvierviertel.ch zugreifen (\u00abNutzer\u00bb). Mittels dieser Datenschutzerkl\u00e4rung m\u00f6chte die Aktion Vierviertel die Nutzer \u00fcber die ihnen zustehenden Rechte aufkl\u00e4ren und die \u00d6ffentlichkeit \u00fcber Art, Umfang und Zweck der erhobenen, genutzten und verarbeiteten personenbezogenen Daten informieren. [&hellip;]<\/p>","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":6,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4053","page","type-page","status-publish","hentry"],"acf":[],"rankMath":{"parentDomain":"aktionvierviertel.ch","noFollowDomains":[],"noFollowExcludeDomains":[],"noFollowExternalLinks":false,"featuredImageNotice":"L\u2019image en vedette devrait \u00eatre au moins 200 par 200 pixels pour \u00eatre utilis\u00e9 par Facebook et d\u2019autres sites de m\u00e9dias sociaux.","pluginReviewed":true,"postSettings":{"linkSuggestions":true,"useFocusKeyword":false},"frontEndScore":false,"postName":"hinweise-zum-datenschutz","permalinkFormat":"https:\/\/aktionvierviertel.ch\/fr\/%pagename%\/","showLockModifiedDate":true,"assessor":{"focusKeywordLink":"https:\/\/aktionvierviertel.ch\/wp-admin\/edit.php?focus_keyword=%focus_keyword%&post_type=%post_type%","hasTOCPlugin":true,"primaryTaxonomy":false,"serpData":{"title":"","description":"Datenschutzrichtlinie - Aktion vierviertel","focusKeywords":"Aktion vierviertel","pillarContent":false,"canonicalUrl":"","breadcrumbTitle":"","advancedRobots":{"max-snippet":"-1","max-video-preview":"-1","max-image-preview":"large"},"facebookTitle":"","facebookDescription":"Wir brauchen einen neuen mutigen Gesellschaftsentwurf. Wer hier lebt, soll ein Recht auf Einb\u00fcrgerung haben. Lass uns gemeinsam die Schweiz ver\u00e4ndern.","facebookImage":"https:\/\/www.aktionvierviertel.ch\/wp-content\/uploads\/2021\/06\/aktion44-sm-preview.jpg","facebookImageID":"5340","facebookHasOverlay":false,"facebookImageOverlay":"","facebookAuthor":"","twitterCardType":"","twitterUseFacebook":true,"twitterTitle":"","twitterDescription":"","twitterImage":"","twitterImageID":"","twitterHasOverlay":false,"twitterImageOverlay":"","twitterPlayerUrl":"","twitterPlayerSize":"","twitterPlayerStream":"","twitterPlayerStreamCtype":"","twitterAppDescription":"","twitterAppIphoneName":"","twitterAppIphoneID":"","twitterAppIphoneUrl":"","twitterAppIpadName":"","twitterAppIpadID":"","twitterAppIpadUrl":"","twitterAppGoogleplayName":"","twitterAppGoogleplayID":"","twitterAppGoogleplayUrl":"","twitterAppCountry":"","robots":{"index":true},"twitterAuthor":"identifiant","primaryTerm":0,"authorName":"George","titleTemplate":"%title% - Aktion Vierviertel - F\u00fcr ein Grundrecht auf Einb\u00fcrgerung","descriptionTemplate":"Wir brauchen einen neuen mutigen Gesellschaftsentwurf. Wer hier lebt, soll ein Recht auf Einb\u00fcrgerung haben. Lass uns gemeinsam die Schweiz ver\u00e4ndern.","showScoreFrontend":true,"lockModifiedDate":false},"powerWords":["absolument","amazement","astonishing","authentique","beau","bien-\u00eatre","brillant","captivant","charismatique","choc","clair","compl\u00e8tement","confidentiel","confiance","cons\u00e9quent","cr\u00e9atif","d\u00e9finitivement","d\u00e9licieux","d\u00e9montrer","d\u00e9p\u00eachez-vous","d\u00e9termin\u00e9","digne","dynamique","\u00e9blouissant","\u00e9clatant","\u00e9conomique","\u00e9fficace","\u00e9l\u00e9gant","\u00e9motionnel","\u00e9nergique","\u00e9norme","\u00e9poustouflant","essentiel","\u00e9tonnant","exclusif","exp\u00e9rience","fabuleux","fantastique","formidable","fort","garanti","g\u00e9ant","g\u00e9n\u00e9reux","grandiose","gratuit","habile","harmonieux","historique","hors pair","important","incroyable","indispensable","inoubliable","inspirant","innovant","intense","invention","irr\u00e9sistible","l\u00e9gendaire","lumineux","luxe","magique","magnifique","majestueux","marquant","merveilleux","miraculeux","motivant","n\u00e9cessaire","nouvelle","officiel","parfait","passionn\u00e9","persuasif","ph\u00e9nom\u00e9nal","plaisir","populaire","pouvoir","prestigieux","prodigieux","profond","prosp\u00e8re","puissant","qualit\u00e9","radieux","rapide","r\u00e9ussi","r\u00e9volutionnaire","satisfait","s\u00e9curit\u00e9","sensationnel","serein","somptueux","splendide","sublime","surprenant","talentueux","terrifiant","unique","valeur","vibrant","victorieux","vif","vraiment","z\u00e9l\u00e9"],"diacritics":{"A":"[\\u0041\\u24B6\\uFF21\\u00C0\\u00C1\\u00C2\\u1EA6\\u1EA4\\u1EAA\\u1EA8\\u00C3\\u0100\\u0102\\u1EB0\\u1EAE\\u1EB4\\u1EB2\\u0226\\u01E0\\u00C4\\u01DE\\u1EA2\\u00C5\\u01FA\\u01CD\\u0200\\u0202\\u1EA0\\u1EAC\\u1EB6\\u1E00\\u0104\\u023A\\u2C6F]","AA":"[\\uA732]","AE":"[\\u00C6\\u01FC\\u01E2]","AO":"[\\uA734]","AU":"[\\uA736]","AV":"[\\uA738\\uA73A]","AY":"[\\uA73C]","B":"[\\u0042\\u24B7\\uFF22\\u1E02\\u1E04\\u1E06\\u0243\\u0182\\u0181]","C":"[\\u0043\\u24B8\\uFF23\\u0106\\u0108\\u010A\\u010C\\u00C7\\u1E08\\u0187\\u023B\\uA73E]","D":"[\\u0044\\u24B9\\uFF24\\u1E0A\\u010E\\u1E0C\\u1E10\\u1E12\\u1E0E\\u0110\\u018B\\u018A\\u0189\\uA779]","DZ":"[\\u01F1\\u01C4]","Dz":"[\\u01F2\\u01C5]","E":"[\\u0045\\u24BA\\uFF25\\u00C8\\u00C9\\u00CA\\u1EC0\\u1EBE\\u1EC4\\u1EC2\\u1EBC\\u0112\\u1E14\\u1E16\\u0114\\u0116\\u00CB\\u1EBA\\u011A\\u0204\\u0206\\u1EB8\\u1EC6\\u0228\\u1E1C\\u0118\\u1E18\\u1E1A\\u0190\\u018E]","F":"[\\u0046\\u24BB\\uFF26\\u1E1E\\u0191\\uA77B]","G":"[\\u0047\\u24BC\\uFF27\\u01F4\\u011C\\u1E20\\u011E\\u0120\\u01E6\\u0122\\u01E4\\u0193\\uA7A0\\uA77D\\uA77E]","H":"[\\u0048\\u24BD\\uFF28\\u0124\\u1E22\\u1E26\\u021E\\u1E24\\u1E28\\u1E2A\\u0126\\u2C67\\u2C75\\uA78D]","I":"[\\u0049\\u24BE\\uFF29\\u00CC\\u00CD\\u00CE\\u0128\\u012A\\u012C\\u0130\\u00CF\\u1E2E\\u1EC8\\u01CF\\u0208\\u020A\\u1ECA\\u012E\\u1E2C\\u0197]","J":"[\\u004A\\u24BF\\uFF2A\\u0134\\u0248]","K":"[\\u004B\\u24C0\\uFF2B\\u1E30\\u01E8\\u1E32\\u0136\\u1E34\\u0198\\u2C69\\uA740\\uA742\\uA744\\uA7A2]","L":"[\\u004C\\u24C1\\uFF2C\\u013F\\u0139\\u013D\\u1E36\\u1E38\\u013B\\u1E3C\\u1E3A\\u0141\\u023D\\u2C62\\u2C60\\uA748\\uA746\\uA780]","LJ":"[\\u01C7]","Lj":"[\\u01C8]","M":"[\\u004D\\u24C2\\uFF2D\\u1E3E\\u1E40\\u1E42\\u2C6E\\u019C]","N":"[\\u004E\\u24C3\\uFF2E\\u01F8\\u0143\\u00D1\\u1E44\\u0147\\u1E46\\u0145\\u1E4A\\u1E48\\u0220\\u019D\\uA790\\uA7A4]","NJ":"[\\u01CA]","Nj":"[\\u01CB]","O":"[\\u004F\\u24C4\\uFF2F\\u00D2\\u00D3\\u00D4\\u1ED2\\u1ED0\\u1ED6\\u1ED4\\u00D5\\u1E4C\\u022C\\u1E4E\\u014C\\u1E50\\u1E52\\u014E\\u022E\\u0230\\u00D6\\u022A\\u1ECE\\u0150\\u01D1\\u020C\\u020E\\u01A0\\u1EDC\\u1EDA\\u1EE0\\u1EDE\\u1EE2\\u1ECC\\u1ED8\\u01EA\\u01EC\\u00D8\\u01FE\\u0186\\u019F\\uA74A\\uA74C]","OI":"[\\u01A2]","OO":"[\\uA74E]","OU":"[\\u0222]","P":"[\\u0050\\u24C5\\uFF30\\u1E54\\u1E56\\u01A4\\u2C63\\uA750\\uA752\\uA754]","Q":"[\\u0051\\u24C6\\uFF31\\uA756\\uA758\\u024A]","R":"[\\u0052\\u24C7\\uFF32\\u0154\\u1E58\\u0158\\u0210\\u0212\\u1E5A\\u1E5C\\u0156\\u1E5E\\u024C\\u2C64\\uA75A\\uA7A6\\uA782]","S":"[\\u0053\\u24C8\\uFF33\\u1E9E\\u015A\\u1E64\\u015C\\u1E60\\u0160\\u1E66\\u1E62\\u1E68\\u0218\\u015E\\u2C7E\\uA7A8\\uA784]","T":"[\\u0054\\u24C9\\uFF34\\u1E6A\\u0164\\u1E6C\\u021A\\u0162\\u1E70\\u1E6E\\u0166\\u01AC\\u01AE\\u023E\\uA786]","TZ":"[\\uA728]","U":"[\\u0055\\u24CA\\uFF35\\u00D9\\u00DA\\u00DB\\u0168\\u1E78\\u016A\\u1E7A\\u016C\\u00DC\\u01DB\\u01D7\\u01D5\\u01D9\\u1EE6\\u016E\\u0170\\u01D3\\u0214\\u0216\\u01AF\\u1EEA\\u1EE8\\u1EEE\\u1EEC\\u1EF0\\u1EE4\\u1E72\\u0172\\u1E76\\u1E74\\u0244]","V":"[\\u0056\\u24CB\\uFF36\\u1E7C\\u1E7E\\u01B2\\uA75E\\u0245]","VY":"[\\uA760]","W":"[\\u0057\\u24CC\\uFF37\\u1E80\\u1E82\\u0174\\u1E86\\u1E84\\u1E88\\u2C72]","X":"[\\u0058\\u24CD\\uFF38\\u1E8A\\u1E8C]","Y":"[\\u0059\\u24CE\\uFF39\\u1EF2\\u00DD\\u0176\\u1EF8\\u0232\\u1E8E\\u0178\\u1EF6\\u1EF4\\u01B3\\u024E\\u1EFE]","Z":"[\\u005A\\u24CF\\uFF3A\\u0179\\u1E90\\u017B\\u017D\\u1E92\\u1E94\\u01B5\\u0224\\u2C7F\\u2C6B\\uA762]","a":"[\\u0061\\u24D0\\uFF41\\u1E9A\\u00E0\\u00E1\\u00E2\\u1EA7\\u1EA5\\u1EAB\\u1EA9\\u00E3\\u0101\\u0103\\u1EB1\\u1EAF\\u1EB5\\u1EB3\\u0227\\u01E1\\u00E4\\u01DF\\u1EA3\\u00E5\\u01FB\\u01CE\\u0201\\u0203\\u1EA1\\u1EAD\\u1EB7\\u1E01\\u0105\\u2C65\\u0250]","aa":"[\\uA733]","ae":"[\\u00E6\\u01FD\\u01E3]","ao":"[\\uA735]","au":"[\\uA737]","av":"[\\uA739\\uA73B]","ay":"[\\uA73D]","b":"[\\u0062\\u24D1\\uFF42\\u1E03\\u1E05\\u1E07\\u0180\\u0183\\u0253]","c":"[\\u0063\\u24D2\\uFF43\\u0107\\u0109\\u010B\\u010D\\u00E7\\u1E09\\u0188\\u023C\\uA73F\\u2184]","d":"[\\u0064\\u24D3\\uFF44\\u1E0B\\u010F\\u1E0D\\u1E11\\u1E13\\u1E0F\\u0111\\u018C\\u0256\\u0257\\uA77A]","dz":"[\\u01F3\\u01C6]","e":"[\\u0065\\u24D4\\uFF45\\u00E8\\u00E9\\u00EA\\u1EC1\\u1EBF\\u1EC5\\u1EC3\\u1EBD\\u0113\\u1E15\\u1E17\\u0115\\u0117\\u00EB\\u1EBB\\u011B\\u0205\\u0207\\u1EB9\\u1EC7\\u0229\\u1E1D\\u0119\\u1E19\\u1E1B\\u0247\\u025B\\u01DD]","f":"[\\u0066\\u24D5\\uFF46\\u1E1F\\u0192\\uA77C]","g":"[\\u0067\\u24D6\\uFF47\\u01F5\\u011D\\u1E21\\u011F\\u0121\\u01E7\\u0123\\u01E5\\u0260\\uA7A1\\u1D79\\uA77F]","h":"[\\u0068\\u24D7\\uFF48\\u0125\\u1E23\\u1E27\\u021F\\u1E25\\u1E29\\u1E2B\\u1E96\\u0127\\u2C68\\u2C76\\u0265]","hv":"[\\u0195]","i":"[\\u0069\\u24D8\\uFF49\\u00EC\\u00ED\\u00EE\\u0129\\u012B\\u012D\\u00EF\\u1E2F\\u1EC9\\u01D0\\u0209\\u020B\\u1ECB\\u012F\\u1E2D\\u0268\\u0131]","j":"[\\u006A\\u24D9\\uFF4A\\u0135\\u01F0\\u0249]","k":"[\\u006B\\u24DA\\uFF4B\\u1E31\\u01E9\\u1E33\\u0137\\u1E35\\u0199\\u2C6A\\uA741\\uA743\\uA745\\uA7A3]","l":"[\\u006C\\u24DB\\uFF4C\\u0140\\u013A\\u013E\\u1E37\\u1E39\\u013C\\u1E3D\\u1E3B\\u017F\\u0142\\u019A\\u026B\\u2C61\\uA749\\uA781\\uA747]","lj":"[\\u01C9]","m":"[\\u006D\\u24DC\\uFF4D\\u1E3F\\u1E41\\u1E43\\u0271\\u026F]","n":"[\\u006E\\u24DD\\uFF4E\\u01F9\\u0144\\u00F1\\u1E45\\u0148\\u1E47\\u0146\\u1E4B\\u1E49\\u019E\\u0272\\u0149\\uA791\\uA7A5]","nj":"[\\u01CC]","o":"[\\u006F\\u24DE\\uFF4F\\u00F2\\u00F3\\u00F4\\u1ED3\\u1ED1\\u1ED7\\u1ED5\\u00F5\\u1E4D\\u022D\\u1E4F\\u014D\\u1E51\\u1E53\\u014F\\u022F\\u0231\\u00F6\\u022B\\u1ECF\\u0151\\u01D2\\u020D\\u020F\\u01A1\\u1EDD\\u1EDB\\u1EE1\\u1EDF\\u1EE3\\u1ECD\\u1ED9\\u01EB\\u01ED\\u00F8\\u01FF\\u0254\\uA74B\\uA74D\\u0275]","oi":"[\\u01A3]","ou":"[\\u0223]","oo":"[\\uA74F]","p":"[\\u0070\\u24DF\\uFF50\\u1E55\\u1E57\\u01A5\\u1D7D\\uA751\\uA753\\uA755]","q":"[\\u0071\\u24E0\\uFF51\\u024B\\uA757\\uA759]","r":"[\\u0072\\u24E1\\uFF52\\u0155\\u1E59\\u0159\\u0211\\u0213\\u1E5B\\u1E5D\\u0157\\u1E5F\\u024D\\u027D\\uA75B\\uA7A7\\uA783]","s":"[\\u0073\\u24E2\\uFF53\\u015B\\u1E65\\u015D\\u1E61\\u0161\\u1E67\\u1E63\\u1E69\\u0219\\u015F\\u023F\\uA7A9\\uA785\\u1E9B]","ss":"[\\u00DF]","t":"[\\u0074\\u24E3\\uFF54\\u1E6B\\u1E97\\u0165\\u1E6D\\u021B\\u0163\\u1E71\\u1E6F\\u0167\\u01AD\\u0288\\u2C66\\uA787]","tz":"[\\uA729]","u":"[\\u0075\\u24E4\\uFF55\\u00F9\\u00FA\\u00FB\\u0169\\u1E79\\u016B\\u1E7B\\u016D\\u00FC\\u01DC\\u01D8\\u01D6\\u01DA\\u1EE7\\u016F\\u0171\\u01D4\\u0215\\u0217\\u01B0\\u1EEB\\u1EE9\\u1EEF\\u1EED\\u1EF1\\u1EE5\\u1E73\\u0173\\u1E77\\u1E75\\u0289]","v":"[\\u0076\\u24E5\\uFF56\\u1E7D\\u1E7F\\u028B\\uA75F\\u028C]","vy":"[\\uA761]","w":"[\\u0077\\u24E6\\uFF57\\u1E81\\u1E83\\u0175\\u1E87\\u1E85\\u1E98\\u1E89\\u2C73]","x":"[\\u0078\\u24E7\\uFF58\\u1E8B\\u1E8D]","y":"[\\u0079\\u24E8\\uFF59\\u1EF3\\u00FD\\u0177\\u1EF9\\u0233\\u1E8F\\u00FF\\u1EF7\\u1E99\\u1EF5\\u01B4\\u024F\\u1EFF]","z":"[\\u007A\\u24E9\\uFF5A\\u017A\\u1E91\\u017C\\u017E\\u1E93\\u1E95\\u01B6\\u0225\\u0240\\u2C6C\\uA763]"},"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasRedirection":false,"hasBreadcrumb":false},"homeUrl":"https:\/\/aktionvierviertel.ch\/fr","objectID":4053,"objectType":"post","locale":"fr","localeFull":"fr_FR","overlayImages":{"play":{"name":"Ic\u00f4ne de lecture","url":"https:\/\/aktionvierviertel.ch\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","path":"\/var\/www\/vhosts\/aktionvierviertel.ch\/httpdocs\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","position":"middle_center"},"gif":{"name":"Ic\u00f4ne GIF","url":"https:\/\/aktionvierviertel.ch\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","path":"\/var\/www\/vhosts\/aktionvierviertel.ch\/httpdocs\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","position":"middle_center"}},"defautOgImage":"https:\/\/www.aktionvierviertel.ch\/wp-content\/uploads\/2021\/06\/cropped-Logovierviertel-023-svg.png","customPermalinks":true,"isUserRegistered":false,"autoSuggestKeywords":false,"connectSiteUrl":"https:\/\/rankmath.com\/auth?site=https%3A%2F%2Faktionvierviertel.ch%2Ffr&r=https%3A%2F%2Faktionvierviertel.ch%2Ffr%2Fwp-json%2Fwp%2Fv2%2Fpages%2F4053%3Fnonce%3Df5d8a92dc0","maxTags":5,"trendsIcon":"<svg viewBox=\"0 0 610 610\"><path d=\"M18.85,446,174.32,290.48l58.08,58.08L76.93,504a14.54,14.54,0,0,1-20.55,0L18.83,466.48a14.54,14.54,0,0,1,0-20.55Z\" style=\"fill:#4285f4\"\/><path d=\"M242.65,242.66,377.59,377.6l-47.75,47.75a14.54,14.54,0,0,1-20.55,0L174.37,290.43l47.75-47.75A14.52,14.52,0,0,1,242.65,242.66Z\" style=\"fill:#ea4335\"\/><polygon points=\"319.53 319.53 479.26 159.8 537.34 217.88 377.61 377.62 319.53 319.53\" style=\"fill:#fabb05\"\/><path d=\"M594.26,262.73V118.61h0a16.94,16.94,0,0,0-16.94-16.94H433.2a16.94,16.94,0,0,0-12,28.92L565.34,274.71h0a16.94,16.94,0,0,0,28.92-12Z\" style=\"fill:#34a853\"\/><rect width=\"610\" height=\"610\" style=\"fill:none\"\/><\/svg>","showScore":true,"siteFavIcon":"https:\/\/aktionvierviertel.ch\/wp-content\/uploads\/2021\/04\/logo-aktion44.png","canUser":{"general":false,"advanced":false,"snippet":false,"social":false,"analysis":false,"analytics":false,"content_ai":false},"showKeywordIntent":true,"isPro":false,"is_front_page":false,"trendsUpgradeLink":"https:\/\/rankmath.com\/pricing\/?utm_source=Plugin&utm_medium=CE%20General%20Tab%20Trends&utm_campaign=WP","trendsUpgradeLabel":"Mettre \u00e0 niveau","trendsPreviewImage":"https:\/\/aktionvierviertel.ch\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/trends-preview.jpg","currentEditor":false,"homepageData":{"assessor":{"powerWords":["absolument","amazement","astonishing","authentique","beau","bien-\u00eatre","brillant","captivant","charismatique","choc","clair","compl\u00e8tement","confidentiel","confiance","cons\u00e9quent","cr\u00e9atif","d\u00e9finitivement","d\u00e9licieux","d\u00e9montrer","d\u00e9p\u00eachez-vous","d\u00e9termin\u00e9","digne","dynamique","\u00e9blouissant","\u00e9clatant","\u00e9conomique","\u00e9fficace","\u00e9l\u00e9gant","\u00e9motionnel","\u00e9nergique","\u00e9norme","\u00e9poustouflant","essentiel","\u00e9tonnant","exclusif","exp\u00e9rience","fabuleux","fantastique","formidable","fort","garanti","g\u00e9ant","g\u00e9n\u00e9reux","grandiose","gratuit","habile","harmonieux","historique","hors pair","important","incroyable","indispensable","inoubliable","inspirant","innovant","intense","invention","irr\u00e9sistible","l\u00e9gendaire","lumineux","luxe","magique","magnifique","majestueux","marquant","merveilleux","miraculeux","motivant","n\u00e9cessaire","nouvelle","officiel","parfait","passionn\u00e9","persuasif","ph\u00e9nom\u00e9nal","plaisir","populaire","pouvoir","prestigieux","prodigieux","profond","prosp\u00e8re","puissant","qualit\u00e9","radieux","rapide","r\u00e9ussi","r\u00e9volutionnaire","satisfait","s\u00e9curit\u00e9","sensationnel","serein","somptueux","splendide","sublime","surprenant","talentueux","terrifiant","unique","valeur","vibrant","victorieux","vif","vraiment","z\u00e9l\u00e9"],"diacritics":true,"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasBreadcrumb":false,"serpData":{"title":"%sitename% %page% %sep% %sitedesc%","description":"","titleTemplate":"%sitename% %page% %sep% %sitedesc%","descriptionTemplate":"","focusKeywords":"","breadcrumbTitle":"Home","robots":{"index":true},"advancedRobots":{"max-snippet":"-1","max-video-preview":"-1","max-image-preview":"large"},"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":""}}},"tocTitle":"Table of Contents","tocExcludeHeadings":[],"listStyle":"ul"},"_links":{"self":[{"href":"https:\/\/aktionvierviertel.ch\/fr\/wp-json\/wp\/v2\/pages\/4053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aktionvierviertel.ch\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/aktionvierviertel.ch\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/aktionvierviertel.ch\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/aktionvierviertel.ch\/fr\/wp-json\/wp\/v2\/comments?post=4053"}],"version-history":[{"count":0,"href":"https:\/\/aktionvierviertel.ch\/fr\/wp-json\/wp\/v2\/pages\/4053\/revisions"}],"wp:attachment":[{"href":"https:\/\/aktionvierviertel.ch\/fr\/wp-json\/wp\/v2\/media?parent=4053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}